{"id":3685,"date":"2021-01-01T15:22:49","date_gmt":"2021-01-01T15:22:49","guid":{"rendered":"http:\/\/hkangles.com\/attarni\/datasite\/?page_id=3685"},"modified":"2026-02-03T14:28:39","modified_gmt":"2026-02-03T14:28:39","slug":"home","status":"publish","type":"page","link":"https:\/\/www.naturajardineria.es\/en\/","title":{"rendered":"Home"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3685\" class=\"elementor elementor-3685\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ca1ea9 elementor-section-stretched cd-bg-color-white elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ca1ea9\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c88f0e3 cd-bg-color-transparent\" data-id=\"c88f0e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffcec71 elementor-widget elementor-widget-heading\" data-id=\"ffcec71\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CUIDADO. BELLEZA. PRECISI\u00d3N.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b454dc4 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"b454dc4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">UN JARD\u00cdN HERMOSO ES OBRA DEL CORAZ\u00d3N<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1942d40 cd-bg-color-secondary elementor-align-left elementor-widget elementor-widget-button\" data-id=\"1942d40\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/servicios\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descubre nuestros servicios<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e3c32a9 elementor-section-stretched cd-bg-color-white elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e3c32a9\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-34c036c cd-bg-color-transparent\" data-id=\"34c036c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed08c4d elementor-widget elementor-widget-hkangles-infobox\" data-id=\"ed08c4d\" data-element_type=\"widget\" data-widget_type=\"hkangles-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hkangles-elementor-widgethkangles_infobox_wrapper infobox-style-6 hkangles-infobox1697158524 icon-type-font\">\n\t\t\t\t<div class=\"hkangles-infobox-wrapper d-flex\">\r\n\t\t\t\t\t\t\t<div class=\"hkangles-infobox-icon\"><i aria-hidden=\"true\" class=\"flaticon flaticon-watering-can\"><\/i><\/div>\r\n\t\t\t\t\t\t\t<div class=\"hkangles-infobox-content\">\r\n\t\t\t\t\t\t\t<h3 class=\"hkangles-infobox-title\">\nPoda y jardiner\u00eda <br> en altura<\/h3>\r\n\t\t\t\t\t\t\t\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2c17e0e cd-bg-color-transparent\" data-id=\"2c17e0e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18ad9e2 elementor-widget elementor-widget-hkangles-infobox\" data-id=\"18ad9e2\" data-element_type=\"widget\" data-widget_type=\"hkangles-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hkangles-elementor-widgethkangles_infobox_wrapper infobox-style-6 hkangles-infobox455849872 icon-type-font\">\n\t\t\t\t<div class=\"hkangles-infobox-wrapper d-flex\">\r\n\t\t\t\t\t\t\t<div class=\"hkangles-infobox-icon\"><i aria-hidden=\"true\" class=\"flaticon flaticon-plant-pot\"><\/i><\/div>\r\n\t\t\t\t\t\t\t<div class=\"hkangles-infobox-content\">\r\n\t\t\t\t\t\t\t<div class=\"hkangles-infobox-text\">\n<\/div>\r\n\t\t\t\t\t\t\t\t<h3 class=\"hkangles-infobox-title\">\nSistemas <br> de riego<\/h3>\r\n\t\t\t\t\t\t\t\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-16c6c88 cd-bg-color-transparent\" data-id=\"16c6c88\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd4d0bf elementor-widget elementor-widget-hkangles-infobox\" data-id=\"fd4d0bf\" data-element_type=\"widget\" data-widget_type=\"hkangles-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hkangles-elementor-widgethkangles_infobox_wrapper infobox-style-6 hkangles-infobox1012552591 icon-type-font\">\n\t\t\t\t<div class=\"hkangles-infobox-wrapper d-flex\">\r\n\t\t\t\t\t\t\t<div class=\"hkangles-infobox-icon\"><i aria-hidden=\"true\" class=\"flaticon flaticon-garden-1\"><\/i><\/div>\r\n\t\t\t\t\t\t\t<div class=\"hkangles-infobox-content\">\r\n\t\t\t\t\t\t\t<div class=\"hkangles-infobox-text\">\n<\/div>\r\n\t\t\t\t\t\t\t\t<h3 class=\"hkangles-infobox-title\">\nDise\u00f1o y<br> paisajismo <\/h3>\r\n\t\t\t\t\t\t\t\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55b4f93 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default cd-bg-color-transparent\" data-id=\"55b4f93\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5d66a42 cd-left-expand cd-bg-color-primary\" data-id=\"5d66a42\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-a41a4dd elementor-section-boxed elementor-section-height-default elementor-section-height-default cd-bg-color-transparent\" data-id=\"a41a4dd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7d81288 cd-bg-color-transparent\" data-id=\"7d81288\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad5b31c elementor-widget elementor-widget-hkangles-custom-heading\" data-id=\"ad5b31c\" data-element_type=\"widget\" data-widget_type=\"hkangles-custom-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hkangles_custom_heading_wrapper hkangles-custom-heading1972711972 custom-heading-style-2 subtitle-text-uppercase title-text- heading-alignment-\">\r\n\t\t\t<div class=\"hkangles-custom-heading-wrapper\">\r\n\t\t\t<div class=\"hkangles-heading-subtitle-wrapper\">\r\n\t\t\t<h3 class=\"heading-subtitle\">\r\n\t\t\t\tSobre nosotros\t\t\t<\/h3>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"hkangles-heading-title-wrapper\">\r\n\t\t\t<h3 class=\"heading-title\">\r\n\t\t\t\tTransformamos tu jard\u00edn en un espacio \u00fanico.\t\t\t<\/h3>\r\n\t\t<\/div>\r\n\t\t<\/div>\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-211544a cd-left-expand cd-bg-color-primary\" data-id=\"211544a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-410e1b7 elementor-widget elementor-widget-image\" data-id=\"410e1b7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/elementor\/thumbs\/home-rdvjewbuc1r6dbmsoo7iam5dmtn523euuhyajn6tcm.jpg\" title=\"Transformamos tu jard\u00edn | Natura Jardiner\u00eda\" alt=\"Transformamos tu jard\u00edn | Natura Jardiner\u00eda\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c27ba39 cd-right-expand cd-bg-color-transparent\" data-id=\"c27ba39\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-f33c04d elementor-section-boxed elementor-section-height-default elementor-section-height-default cd-bg-color-transparent\" data-id=\"f33c04d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4c09d2f cd-bg-color-transparent\" data-id=\"4c09d2f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3389ac8 elementor-widget elementor-widget-text-editor\" data-id=\"3389ac8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Somos expertos creando, manteniendo y transformando espacios verdes con profesionalidad, seguridad y dise\u00f1o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-4eac12d elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default cd-bg-color-transparent\" data-id=\"4eac12d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5d5216f cd-bg-color-transparent\" data-id=\"5d5216f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0163011 cd-bg-color-secondary elementor-widget elementor-widget-button\" data-id=\"0163011\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/sobre-nosotros\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Con\u00f3cenos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bcbe4c6 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default cd-bg-color-transparent\" data-id=\"bcbe4c6\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-eb945a1 cd-left-expand cd-bg-color-tertiary elementor-col-fix-width hkangles-background-overlay\" data-id=\"eb945a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46d538b elementor-widget elementor-widget-hkangles-custom-heading\" data-id=\"46d538b\" data-element_type=\"widget\" data-widget_type=\"hkangles-custom-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hkangles_custom_heading_wrapper hkangles-custom-heading853531610 custom-heading-style-1 subtitle-text-uppercase title-text-capitalize heading-alignment-\">\r\n\t\t\t<div class=\"hkangles-custom-heading-wrapper\">\r\n\t\t\t<div class=\"hkangles-heading-subtitle-wrapper\">\r\n\t\t\t<h3 class=\"heading-subtitle\">\r\n\t\t\t\tLos mejores servicios para ti\t\t\t<\/h3>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"hkangles-heading-title-wrapper\">\r\n\t\t\t<h3 class=\"heading-title\">\r\n\t\t\t\tCuando plantas una semilla, plantas esperanza.\t\t\t<\/h3>\r\n\t\t<\/div>\r\n\t\t<\/div>\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54fa89f elementor-widget elementor-widget-hkangles-infobox\" data-id=\"54fa89f\" data-element_type=\"widget\" data-widget_type=\"hkangles-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hkangles-elementor-widgethkangles_infobox_wrapper infobox-style-1 hkangles-infobox894397406 icon-type-font\">\n\t\t\t<div class=\"hkangles-infobox-wrapper d-flex align-items-center\">\r\n\t\t\t\t\t<div class=\"hkangles-infobox-icon\"><i aria-hidden=\"true\" class=\"flaticon flaticon-watering-can\"><\/i><\/div>\r\n\t\t\t\t\t<div class=\"hkangles-infobox-content\">\r\n\t\t\t\t\t<h3 class=\"hkangles-infobox-title\">M\u00e1s de 100 personas eligen nuestros servicios de jardiner\u00eda y paisajismo.<\/h3>\r\n\t\t\t\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9813ff9 cd-bg-color-white\" data-id=\"9813ff9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ce1878 elementor-widget elementor-widget-planto-services\" data-id=\"7ce1878\" data-element_type=\"widget\" data-widget_type=\"planto-services.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hkangles-elementor-widget hkangles_services_wrappers services-style-1 services-layout-slider\">\n\t\t\t<div class=\"owl-carousel owl-theme hkangles-service-wrappers\" data-owl_options=\"{&quot;items&quot;:&quot;3&quot;,&quot;loop&quot;:&quot;&quot;,&quot;margin&quot;:30,&quot;nav&quot;:&quot;&quot;,&quot;dots&quot;:&quot;&quot;,&quot;autoplay&quot;:&quot;&quot;,&quot;smartSpeed&quot;:1000,&quot;navText&quot;:[&quot;&lt;i class=&#039;flaticon flaticon-left-arrow&#039;&gt;&lt;\\\/i&gt;&quot;,&quot;&lt;i class=&#039;flaticon flaticon-right-arrow&#039;&gt;&lt;\\\/i&gt;&quot;],&quot;responsive&quot;:{&quot;0&quot;:{&quot;items&quot;:1},&quot;576&quot;:{&quot;items&quot;:2},&quot;768&quot;:{&quot;items&quot;:3},&quot;992&quot;:{&quot;items&quot;:3}}}\">\r\n\t<div class=\"hkangles-service-slide\">\r\n\t<div class=\"hkangles-service-service-wrapper\">\r\n\t\t<div class=\"hkangles-service-thumbnail-wrapper\">\r\n\t\t\t\t\t\t<div class=\"hkangles-service-image-container\">\r\n\t\t\t\t<div class=\"hkangles-service-image-overlap\"> <\/div>\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"hkangles-service-image\" src=\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2021\/03\/poda-600x650.jpg\" alt=\"Poda y jardiner\u00eda en altura\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"hkangles-service-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"flaticon-plants\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\t\t\t\t\t\r\n\t\t<\/div>\t\t\t\t\r\n\t\t<div class=\"hkangles-service-content-inner\">\r\n\t\t\t<div class=\"hkangles-service-content-inner-area\">\r\n\t\t\t\t<div class=\"hkangles-service-content-cover\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"hkangles-service-title-wrap\">\r\n\t\t\t\t\t\t<h3 class=\"hkangles-service-title\"><a href=\"https:\/\/www.naturajardineria.es\/en\/service\/poda-y-jardineria-en-altura\/\">Poda y jardiner\u00eda en altura<\/a><\/h3>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"hkangles-service-slide\">\r\n\t<div class=\"hkangles-service-service-wrapper\">\r\n\t\t<div class=\"hkangles-service-thumbnail-wrapper\">\r\n\t\t\t\t\t\t<div class=\"hkangles-service-image-container\">\r\n\t\t\t\t<div class=\"hkangles-service-image-overlap\"> <\/div>\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"hkangles-service-image\" src=\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2021\/03\/pisajismo-600x650.jpg\" alt=\"Dise\u00f1o y paisajismo\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"hkangles-service-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"flaticon-ecology\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\t\t\t\t\t\r\n\t\t<\/div>\t\t\t\t\r\n\t\t<div class=\"hkangles-service-content-inner\">\r\n\t\t\t<div class=\"hkangles-service-content-inner-area\">\r\n\t\t\t\t<div class=\"hkangles-service-content-cover\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"hkangles-service-title-wrap\">\r\n\t\t\t\t\t\t<h3 class=\"hkangles-service-title\"><a href=\"https:\/\/www.naturajardineria.es\/en\/service\/diseno-y-paisajismo\/\">Dise\u00f1o y paisajismo<\/a><\/h3>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"hkangles-service-slide\">\r\n\t<div class=\"hkangles-service-service-wrapper\">\r\n\t\t<div class=\"hkangles-service-thumbnail-wrapper\">\r\n\t\t\t\t\t\t<div class=\"hkangles-service-image-container\">\r\n\t\t\t\t<div class=\"hkangles-service-image-overlap\"> <\/div>\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"hkangles-service-image\" src=\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2021\/03\/sistema-de-riego-600x650.jpg\" alt=\"Montaje de sistemas de riego\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"hkangles-service-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"flaticon-watering-can\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\t\t\t\t\t\r\n\t\t<\/div>\t\t\t\t\r\n\t\t<div class=\"hkangles-service-content-inner\">\r\n\t\t\t<div class=\"hkangles-service-content-inner-area\">\r\n\t\t\t\t<div class=\"hkangles-service-content-cover\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"hkangles-service-title-wrap\">\r\n\t\t\t\t\t\t<h3 class=\"hkangles-service-title\"><a href=\"https:\/\/www.naturajardineria.es\/en\/service\/montaje-de-sistemas-de-riego\/\">Montaje de sistemas de riego<\/a><\/h3>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"hkangles-service-slide\">\r\n\t<div class=\"hkangles-service-service-wrapper\">\r\n\t\t<div class=\"hkangles-service-thumbnail-wrapper\">\r\n\t\t\t\t\t\t<div class=\"hkangles-service-image-container\">\r\n\t\t\t\t<div class=\"hkangles-service-image-overlap\"> <\/div>\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"hkangles-service-image\" src=\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2020\/06\/mantenimiento-600x650.jpg\" alt=\"Mantenimiento integral\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"hkangles-service-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"flaticon-plant-pot\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\t\t\t\t\t\r\n\t\t<\/div>\t\t\t\t\r\n\t\t<div class=\"hkangles-service-content-inner\">\r\n\t\t\t<div class=\"hkangles-service-content-inner-area\">\r\n\t\t\t\t<div class=\"hkangles-service-content-cover\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"hkangles-service-title-wrap\">\r\n\t\t\t\t\t\t<h3 class=\"hkangles-service-title\"><a href=\"https:\/\/www.naturajardineria.es\/en\/service\/mantenimiento-integral\/\">Mantenimiento integral<\/a><\/h3>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"hkangles-service-slide\">\r\n\t<div class=\"hkangles-service-service-wrapper\">\r\n\t\t<div class=\"hkangles-service-thumbnail-wrapper\">\r\n\t\t\t\t\t\t<div class=\"hkangles-service-image-container\">\r\n\t\t\t\t<div class=\"hkangles-service-image-overlap\"> <\/div>\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"hkangles-service-image\" src=\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2020\/06\/reformas-600x650.jpg\" alt=\"Obras y reformas de jardines\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"hkangles-service-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"flaticon-planting\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\t\t\t\t\t\r\n\t\t<\/div>\t\t\t\t\r\n\t\t<div class=\"hkangles-service-content-inner\">\r\n\t\t\t<div class=\"hkangles-service-content-inner-area\">\r\n\t\t\t\t<div class=\"hkangles-service-content-cover\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"hkangles-service-title-wrap\">\r\n\t\t\t\t\t\t<h3 class=\"hkangles-service-title\"><a href=\"https:\/\/www.naturajardineria.es\/en\/service\/obras-y-reformas-de-jardines\/\">Obras y reformas de jardines<\/a><\/h3>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-adc961a elementor-section-stretched cd-bg-color-tertiary elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"adc961a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38c2059 cd-bg-color-transparent\" data-id=\"38c2059\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-fb766a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default cd-bg-color-transparent\" data-id=\"fb766a1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d3ddaea cd-bg-color-primary hkangles-video-circle\" data-id=\"d3ddaea\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14347c1 elementor-widget elementor-widget-hkangles-infobox\" data-id=\"14347c1\" data-element_type=\"widget\" data-widget_type=\"hkangles-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hkangles-elementor-widgethkangles_infobox_wrapper infobox-style-3 hkangles-infobox1581169247\">\n\t\t\t<div class=\"hkangles-infobox-wrapper d-flex align-items-center\">\r\n\t\t<div class=\"hkangles-infobox-content\">\r\n\t\t\t\t\t<h3 class=\"hkangles-infobox-title\">Cultiva tu jard\u00edn como si fueras a vivir eternamente.<\/h3>\r\n\t\t\t\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6cad648 cd-bg-color-transparent\" data-id=\"6cad648\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15ce597 elementor-section-stretched cd-bg-color-tertiary elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15ce597\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ce2cf4 cd-bg-color-transparent\" data-id=\"6ce2cf4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8be4cf elementor-widget elementor-widget-hkangles-custom-heading\" data-id=\"d8be4cf\" data-element_type=\"widget\" data-widget_type=\"hkangles-custom-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hkangles_custom_heading_wrapper hkangles-custom-heading2033291823 custom-heading-style-1 subtitle-text-uppercase title-text-capitalize heading-alignment-center\">\r\n\t\t\t<div class=\"hkangles-custom-heading-wrapper\">\r\n\t\t\t<div class=\"hkangles-heading-subtitle-wrapper\">\r\n\t\t\t<h3 class=\"heading-subtitle\">\r\n\t\t\t\tPor qu\u00e9 elegirnos\t\t\t<\/h3>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"hkangles-heading-title-wrapper\">\r\n\t\t\t<h3 class=\"heading-title\">\r\n\t\t\t\tPor qu\u00e9 Natura Jardiner\u00eda\t\t\t<\/h3>\r\n\t\t<\/div>\r\n\t\t<\/div>\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-5f364a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default cd-bg-color-transparent\" data-id=\"5f364a9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-83fcbe0 cd-bg-color-transparent\" data-id=\"83fcbe0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8d3869 elementor-widget elementor-widget-hkangles-infobox\" data-id=\"e8d3869\" data-element_type=\"widget\" data-widget_type=\"hkangles-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hkangles-elementor-widgethkangles_infobox_wrapper infobox-style-5 hkangles-infobox1693004077 icon-type-image\">\n\t\t\t<div class=\"hkangles-infobox-wrapper\">\r\n\t\t\t\t<div class=\"hkangles-infobox-img\">\r\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2021\/06\/icon-1.png\" alt=\"Icon\">\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"hkangles-infobox-content justify-content-center align-self-center\">\r\n\t\t\t\t\t<h3 class=\"hkangles-infobox-title\">Mantenimiento de jardines<\/h3>\r\n\t\t\t\t\t\t<div class=\"hkangles-infobox-text\">Limpieza, corte de c\u00e9sped, abonado, control de plagas y enfermedades, y mantenimiento estacional. Nos encargamos de que tu jard\u00edn est\u00e9 siempre impecable.<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-cf50a1e cd-bg-color-transparent\" data-id=\"cf50a1e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b3e27a elementor-widget elementor-widget-hkangles-infobox\" data-id=\"3b3e27a\" data-element_type=\"widget\" data-widget_type=\"hkangles-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hkangles-elementor-widgethkangles_infobox_wrapper infobox-style-5 hkangles-infobox2000600939 icon-type-image\">\n\t\t\t<div class=\"hkangles-infobox-wrapper\">\r\n\t\t\t\t<div class=\"hkangles-infobox-img\">\r\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2021\/07\/icon-3.png\" alt=\"Icon\">\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"hkangles-infobox-content justify-content-center align-self-center\">\r\n\t\t\t\t\t<h3 class=\"hkangles-infobox-title\">Poda y jardiner\u00eda en altura<\/h3>\r\n\t\t\t\t\t\t<div class=\"hkangles-infobox-text\">Especialistas en trabajos de poda profesional, tala y jardiner\u00eda en altura con las m\u00e1ximas garant\u00edas de seguridad. Contamos con personal formado y equipos espec\u00edficos para cada tipo de intervenci\u00f3n.<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d175433 cd-bg-color-transparent\" data-id=\"d175433\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2501b42 elementor-widget elementor-widget-hkangles-infobox\" data-id=\"2501b42\" data-element_type=\"widget\" data-widget_type=\"hkangles-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hkangles-elementor-widgethkangles_infobox_wrapper infobox-style-5 hkangles-infobox910409779 icon-type-image\">\n\t\t\t<div class=\"hkangles-infobox-wrapper\">\r\n\t\t\t\t<div class=\"hkangles-infobox-img\">\r\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2021\/07\/icon-2.png\" alt=\"Icon\">\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"hkangles-infobox-content justify-content-center align-self-center\">\r\n\t\t\t\t\t<h3 class=\"hkangles-infobox-title\">Dise\u00f1o de jardines y paisajismo<\/h3>\r\n\t\t\t\t\t\t<div class=\"hkangles-infobox-text\">Creamos espacios verdes \u00fanicos y adaptados a tu estilo. Dise\u00f1amos jardines que combinan est\u00e9tica, funcionalidad y sostenibilidad.<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c629b26 cd-bg-color-transparent\" data-id=\"c629b26\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c83445 elementor-widget elementor-widget-hkangles-infobox\" data-id=\"3c83445\" data-element_type=\"widget\" data-widget_type=\"hkangles-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hkangles-elementor-widgethkangles_infobox_wrapper infobox-style-5 hkangles-infobox970923003 icon-type-image\">\n\t\t\t<div class=\"hkangles-infobox-wrapper\">\r\n\t\t\t\t<div class=\"hkangles-infobox-img\">\r\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2021\/06\/icon-4.png\" alt=\"Icon\">\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"hkangles-infobox-content justify-content-center align-self-center\">\r\n\t\t\t\t\t<h3 class=\"hkangles-infobox-title\">Montaje de sistemas de riego<\/h3>\r\n\t\t\t\t\t\t<div class=\"hkangles-infobox-text\">Instalaci\u00f3n y mantenimiento de sistemas de riego autom\u00e1ticos y personalizados para cada tipo de terreno y vegetaci\u00f3n.<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-6c46c2e elementor-section-boxed elementor-section-height-default elementor-section-height-default cd-bg-color-transparent\" data-id=\"6c46c2e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-579676b cd-bg-color-transparent\" data-id=\"579676b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80d2800 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"80d2800\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"hkangles-infobox-all-wrap\">For More Information About Us! <a class=\"skincolor\" href=\"#\">\u00a0Click here <i class=\"hkangles-base-icon-right\"><\/i><\/a> <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa5f3a8 cd-bg-color-secondary elementor-align-center elementor-widget elementor-widget-button\" data-id=\"aa5f3a8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/tu-presupuesto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Pide un presupuesto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-6e07931 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default cd-bg-color-transparent\" data-id=\"6e07931\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64344d0 cd-bg-color-transparent\" data-id=\"64344d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1bbc65 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b1bbc65\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"flaticon flaticon-watering-can-1\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33c0d7d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"33c0d7d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Estamos aqu\u00ed para ayudarte a hacer realidad tu sue\u00f1o ecol\u00f3gico.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9444a6f cd-bg-color-primary elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9444a6f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cont\u00e1ctanos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-89a07a4 elementor-section-stretched cd-bg-color-white elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"89a07a4\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42aa0ae cd-bg-color-transparent\" data-id=\"42aa0ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7ca9c1 elementor-widget elementor-widget-image\" data-id=\"f7ca9c1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"59\" src=\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2025\/10\/Logo-digitalizadores-1024x95.png\" class=\"attachment-large size-large wp-image-13553\" alt=\"\" srcset=\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2025\/10\/Logo-digitalizadores-1024x95.png 1024w, https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2025\/10\/Logo-digitalizadores-300x28.png 300w, https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2025\/10\/Logo-digitalizadores-768x71.png 768w, https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2025\/10\/Logo-digitalizadores-1536x143.png 1536w, https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2025\/10\/Logo-digitalizadores.png 1626w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d3af21 elementor-widget elementor-widget-text-editor\" data-id=\"6d3af21\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u00a9 Copyright \u2013 <span data-sheets-root=\"1\">Natura Jardiner\u00eda S. Coop. Peque\u00f1a<\/span>\u00a0| Dise\u00f1o y desarrollo \u2013 <a style=\"font-weight: 600; color: #0a875a;\" href=\"https:\/\/www.essedi.es\/\">Essedi IT\u00a0<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>CUIDADO. BELLEZA. PRECISI\u00d3N. UN JARD\u00cdN HERMOSO ES OBRA DEL CORAZ\u00d3N Descubre nuestros servicios Poda y jardiner\u00eda en altura Sistemas de riego Dise\u00f1o y paisajismo Sobre nosotros Transformamos tu jard\u00edn en un espacio \u00fanico. Somos expertos creando, manteniendo y transformando espacios verdes con profesionalidad, seguridad y dise\u00f1o. Con\u00f3cenos Los mejores servicios para ti Cuando plantas una [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3685","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Home - Natura Jardiner\u00eda<\/title>\n<meta name=\"description\" content=\"Expertos en mantenimiento de jardines, poda en altura, paisajismo y riegos. Cuidamos cada detalle con profesionalidad y seguridad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naturajardineria.es\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - Natura Jardiner\u00eda\" \/>\n<meta property=\"og:description\" content=\"Expertos en mantenimiento de jardines, poda en altura, paisajismo y riegos. Cuidamos cada detalle con profesionalidad y seguridad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naturajardineria.es\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Natura Jardiner\u00eda\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T14:28:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/elementor\/thumbs\/home-rdvjewbuc1r6dbmsoo7iam5dmtn523euuhyajn6tcm.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.naturajardineria.es\/\",\"url\":\"https:\/\/www.naturajardineria.es\/\",\"name\":\"Home - Natura Jardiner\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/www.naturajardineria.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.naturajardineria.es\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.naturajardineria.es\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/elementor\/thumbs\/home-rdvjewbuc1r6dbmsoo7iam5dmtn523euuhyajn6tcm.jpg\",\"datePublished\":\"2021-01-01T15:22:49+00:00\",\"dateModified\":\"2026-02-03T14:28:39+00:00\",\"description\":\"Expertos en mantenimiento de jardines, poda en altura, paisajismo y riegos. Cuidamos cada detalle con profesionalidad y seguridad.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.naturajardineria.es\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.naturajardineria.es\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.naturajardineria.es\/#primaryimage\",\"url\":\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/elementor\/thumbs\/home-rdvjewbuc1r6dbmsoo7iam5dmtn523euuhyajn6tcm.jpg\",\"contentUrl\":\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/elementor\/thumbs\/home-rdvjewbuc1r6dbmsoo7iam5dmtn523euuhyajn6tcm.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.naturajardineria.es\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.naturajardineria.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.naturajardineria.es\/#website\",\"url\":\"https:\/\/www.naturajardineria.es\/\",\"name\":\"Natura Jardiner\u00eda\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.naturajardineria.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.naturajardineria.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.naturajardineria.es\/#organization\",\"name\":\"Natura Jardiner\u00eda\",\"url\":\"https:\/\/www.naturajardineria.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.naturajardineria.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2025\/10\/cropped-Mesa-de-trabajo-1.png\",\"contentUrl\":\"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2025\/10\/cropped-Mesa-de-trabajo-1.png\",\"width\":250,\"height\":250,\"caption\":\"Natura Jardiner\u00eda\"},\"image\":{\"@id\":\"https:\/\/www.naturajardineria.es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - Natura Jardiner\u00eda","description":"Expertos en mantenimiento de jardines, poda en altura, paisajismo y riegos. Cuidamos cada detalle con profesionalidad y seguridad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naturajardineria.es\/en\/","og_locale":"en_GB","og_type":"article","og_title":"Home - Natura Jardiner\u00eda","og_description":"Expertos en mantenimiento de jardines, poda en altura, paisajismo y riegos. Cuidamos cada detalle con profesionalidad y seguridad.","og_url":"https:\/\/www.naturajardineria.es\/en\/","og_site_name":"Natura Jardiner\u00eda","article_modified_time":"2026-02-03T14:28:39+00:00","og_image":[{"url":"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/elementor\/thumbs\/home-rdvjewbuc1r6dbmsoo7iam5dmtn523euuhyajn6tcm.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.naturajardineria.es\/","url":"https:\/\/www.naturajardineria.es\/","name":"Home - Natura Jardiner\u00eda","isPartOf":{"@id":"https:\/\/www.naturajardineria.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.naturajardineria.es\/#primaryimage"},"image":{"@id":"https:\/\/www.naturajardineria.es\/#primaryimage"},"thumbnailUrl":"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/elementor\/thumbs\/home-rdvjewbuc1r6dbmsoo7iam5dmtn523euuhyajn6tcm.jpg","datePublished":"2021-01-01T15:22:49+00:00","dateModified":"2026-02-03T14:28:39+00:00","description":"Expertos en mantenimiento de jardines, poda en altura, paisajismo y riegos. Cuidamos cada detalle con profesionalidad y seguridad.","breadcrumb":{"@id":"https:\/\/www.naturajardineria.es\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naturajardineria.es\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.naturajardineria.es\/#primaryimage","url":"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/elementor\/thumbs\/home-rdvjewbuc1r6dbmsoo7iam5dmtn523euuhyajn6tcm.jpg","contentUrl":"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/elementor\/thumbs\/home-rdvjewbuc1r6dbmsoo7iam5dmtn523euuhyajn6tcm.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.naturajardineria.es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.naturajardineria.es\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/www.naturajardineria.es\/#website","url":"https:\/\/www.naturajardineria.es\/","name":"Natura Jardiner\u00eda","description":"","publisher":{"@id":"https:\/\/www.naturajardineria.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naturajardineria.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.naturajardineria.es\/#organization","name":"Natura Jardiner\u00eda","url":"https:\/\/www.naturajardineria.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.naturajardineria.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2025\/10\/cropped-Mesa-de-trabajo-1.png","contentUrl":"https:\/\/www.naturajardineria.es\/wp-content\/uploads\/2025\/10\/cropped-Mesa-de-trabajo-1.png","width":250,"height":250,"caption":"Natura Jardiner\u00eda"},"image":{"@id":"https:\/\/www.naturajardineria.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.naturajardineria.es\/en\/wp-json\/wp\/v2\/pages\/3685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naturajardineria.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.naturajardineria.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.naturajardineria.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naturajardineria.es\/en\/wp-json\/wp\/v2\/comments?post=3685"}],"version-history":[{"count":121,"href":"https:\/\/www.naturajardineria.es\/en\/wp-json\/wp\/v2\/pages\/3685\/revisions"}],"predecessor-version":[{"id":13803,"href":"https:\/\/www.naturajardineria.es\/en\/wp-json\/wp\/v2\/pages\/3685\/revisions\/13803"}],"wp:attachment":[{"href":"https:\/\/www.naturajardineria.es\/en\/wp-json\/wp\/v2\/media?parent=3685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}